{"id":136,"count":1,"description":"","link":"https:\/\/captainelectric.ca\/blog\/tag\/electrical-panel-replacement\/","name":"electrical panel replacement","slug":"electrical-panel-replacement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/captainelectric.ca\/blog\/wp-json\/wp\/v2\/tags\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/captainelectric.ca\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/captainelectric.ca\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/captainelectric.ca\/blog\/wp-json\/wp\/v2\/posts?tags=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}